{"id":2701,"date":"2020-06-18T12:17:25","date_gmt":"2020-06-18T12:17:25","guid":{"rendered":"https:\/\/casevacanzecefalu.com\/listing\/oceano\/"},"modified":"2023-03-19T18:21:58","modified_gmt":"2023-03-19T18:21:58","slug":"oceano-appartamento-cefalu","status":"publish","type":"listing","link":"https:\/\/casevacanzecefalu.com\/de\/listing\/oceano-appartamento-cefalu\/","title":{"rendered":"Oceano"},"content":{"rendered":"<p>Oceano \u00e8 l\u2019appartamento ideale per chi vuole trascorrere una vacanza tra cultura e mare, in una\u00a0sistemazione modernamente arredata.<\/p>\n<p>La posizione dell\u2019alloggio \u00e8 comoda per visitare il centro storico, raggiungendo facilmente sia la cattedrale che il museo Mandralisca che si trovano a pochi passi dall\u2019appartamento mentre la spiaggia \u00e8 molto pi\u00f9 vicina soli 2 minuti a piedi , permette di trascorrere una vacanza senza utilizzare l&#8217;auto, dal momento che l&#8217;alloggio si trova in una zona a traffico limitato.<\/p>\n<p>L&#8217;abitazione \u00e8 una soluzione ideale per un gruppo familiare e permette di trascorrere un soggiorno godendo delle passeggiate tra le strade del centro storico, la spiaggia del lungomare e anche sulla rocca di Cefal\u00f9<br \/>\n\u00e8 la sistemazione perfetta per chi \u00e8 alla ricerca di un\u00a0luogo curato nei dettagli, accogliente e dove potersi sentire come a casa propria, un posto ideale per vivere i colori, i sapori e la cultura cefaludese.<\/p>\n<p>L&#8217;appartamento \u00e8 di circa 50 mq si trova al piano terra e ha 2 letti matrimoniali, una cucina, un bagno con doccia balcone a petto e nella stanza da letto anche una finestra che da a un cortile.<\/p>\n<p>Fornito dai confort come: Wi-Fi, in ogni stanza c&#8217;\u00e8 una TV , climatizzatore situato nella cucina, asse e ferro da stiro, asciuga mani, telo doccia, asciuga capelli, strofinaccio, padelle, piatti, posate e lavatrice. I servizi inclusi sono: biancheria pulizia finale e consumi. Pu\u00f2 ospitare comodamente 4 persone. Disponibile parcheggio privato in zona su prenotazione.<\/p>\n<p><span style=\"color: #ff0000\">Listino per 4 persone 2023<\/span>:<br \/>\n<em>Gennaio<\/em> :<strong>a notte<\/strong> \u20ac 125\u00a0 \u00a0 \u00a0<strong>per 3 notti<\/strong> \u20ac 260\u00a0 \u00a0 \u00a0<strong>per 7 notti<\/strong> \u20ac 500<\/p>\n<p><em>Febbraio<\/em>: <strong>a notte<\/strong> \u20ac125\u00a0 \u00a0 \u00a0 <strong>per 3 notti<\/strong> \u20ac 260\u00a0 \u00a0 \u00a0 <strong>per 7 notti<\/strong> \u20ac500<\/p>\n<p><em>Marzo<\/em>: <strong>a notte<\/strong> \u20ac125\u00a0 \u00a0<strong>per 3 notti<\/strong> \u20ac 260\u00a0 \u00a0<strong>per 7 notti\u00a0<\/strong>\u20ac500<\/p>\n<p><em>Aprile<\/em>: <strong>a notte<\/strong> \u20ac 130\u00a0 <strong>per 3 notti<\/strong> \u20ac275\u00a0 \u00a0 <strong>per 7 notti<\/strong> \u20ac500<\/p>\n<p><em>Maggio<\/em>:\u00a0<strong>a notte<\/strong> \u20ac130\u00a0 <strong>per 3 notti<\/strong> \u20ac300\u00a0 \u00a0 <strong>per 7 notti<\/strong> \u20ac500<\/p>\n<p><em>Giugno<\/em>: <strong>a notte<\/strong> \u20ac145\u00a0 \u00a0<strong>per 3 notti<\/strong> \u20ac300\u00a0 <strong>per 7 notti\u00a0<\/strong>\u20ac500<\/p>\n<p><em>Luglio: dal 01\/07\/22 al 15\/07\/22<\/em> <strong>a notte<\/strong> \u20ac150<\/p>\n<p><em>Luglio: dal 16\/07\/22 al 31\/07\/22<\/em> <strong>a notte<\/strong> \u20ac160<\/p>\n<p><em>Agosto giorno 14\/08\/22<\/em> \u20ac500<br \/>\n<em>Agosto giorno 15\/08\/22<\/em> \u20ac300<\/p>\n<p><em>Agosto: dal 01\/08\/22 al 20\/08\/22<\/em> \u00a0\u20ac180<\/p>\n<p><em>Fine agosto: dal 21\/08\/22 al 31\/08\/22<\/em> \u00a0\u20ac160<\/p>\n<p><em>Settembre<\/em>: <strong>a notte<\/strong> \u20ac 140\u00a0 \u00a0 <strong>per 3 notti<\/strong> \u20ac360\u00a0 \u00a0<strong>per 7 notti<\/strong> \u20ac770<\/p>\n<p><em>Ottobre<\/em>: <strong>a notte<\/strong> \u20ac 130\u00a0 \u00a0 <strong>per 3 notti<\/strong> \u20ac 300\u00a0 \u00a0 <strong>per 7 notti<\/strong> \u20ac500<\/p>\n<p><em>Novembre<\/em>: <strong>a notte<\/strong> \u20ac125\u00a0 \u00a0 <strong>\u00a0per 3 notti<\/strong> \u20ac260\u00a0 \u00a0 \u00a0<strong>\u00a0per 7 notti<\/strong> \u20ac500<\/p>\n<p><em>Dicembre<\/em>: <strong>a notte<\/strong> \u20ac 125\u00a0 \u00a0 <strong>per 3 notti<\/strong> \u20ac 260\u00a0 \u00a0\u00a0<strong> per 7 notti<\/strong> \u20ac500<\/p>\nngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"<p>Oceano \u00e8 l\u2019appartamento ideale per chi vuole trascorrere una vacanza tra cultura e mare, in una\u00a0sistemazione modernamente arredata. La posizione dell\u2019alloggio \u00e8 comoda per visitare il centro storico, raggiungendo facilmente sia la cattedrale che il museo Mandralisca che si trovano a pochi passi dall\u2019appartamento mentre la spiaggia \u00e8 molto pi\u00f9 vicina soli 2 minuti a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2729,"parent":0,"menu_order":0,"template":"","meta":{"ngg_post_thumbnail":0,"_joinchat":[],"footnotes":""},"listing_type":[37],"room_type":[24],"amenities":[12,30,19,40,32,44,31],"facilities":[],"listing_countries":[41],"listing_states":[42],"listing_cities":[43],"listing_areas":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Oceano - Case Vacanze Cefal\u00f9<\/title>\n<meta name=\"description\" content=\"Appartamento di 50 mq a Cefal\u00f9 a pochi passi dal mare e dal centro storico ideale per la famiglia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oceano - Case Vacanze Cefal\u00f9\" \/>\n<meta property=\"og:description\" content=\"Appartamento di 50 mq a Cefal\u00f9 a pochi passi dal mare e dal centro storico ideale per la famiglia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/\" \/>\n<meta property=\"og:site_name\" content=\"Case Vacanze Cefal\u00f9\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-19T18:21:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casevacanzecefalu.com\/wp-content\/uploads\/2020\/06\/IMG_1392.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/\",\"url\":\"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/\",\"name\":\"Oceano - Case Vacanze Cefal\u00f9\",\"isPartOf\":{\"@id\":\"https:\/\/casevacanzecefalu.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casevacanzecefalu.com\/wp-content\/uploads\/2020\/06\/IMG_1392.jpg\",\"datePublished\":\"2020-06-18T12:17:25+00:00\",\"dateModified\":\"2023-03-19T18:21:58+00:00\",\"description\":\"Appartamento di 50 mq a Cefal\u00f9 a pochi passi dal mare e dal centro storico ideale per la famiglia\",\"breadcrumb\":{\"@id\":\"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/#primaryimage\",\"url\":\"https:\/\/casevacanzecefalu.com\/wp-content\/uploads\/2020\/06\/IMG_1392.jpg\",\"contentUrl\":\"https:\/\/casevacanzecefalu.com\/wp-content\/uploads\/2020\/06\/IMG_1392.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/casevacanzecefalu.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\/\/casevacanzecefalu.com\/listing\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Oceano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casevacanzecefalu.com\/#website\",\"url\":\"https:\/\/casevacanzecefalu.com\/\",\"name\":\"Case Vacanze Cefal\u00f9\",\"description\":\"affitto case ed appartamenti a Cefal\u00f9\",\"publisher\":{\"@id\":\"https:\/\/casevacanzecefalu.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casevacanzecefalu.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casevacanzecefalu.com\/#organization\",\"name\":\"Case Vacanze Cefal\u00f9\",\"url\":\"https:\/\/casevacanzecefalu.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/casevacanzecefalu.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casevacanzecefalu.com\/wp-content\/uploads\/2019\/12\/casevacanzacefalu.png\",\"contentUrl\":\"https:\/\/casevacanzecefalu.com\/wp-content\/uploads\/2019\/12\/casevacanzacefalu.png\",\"width\":300,\"height\":73,\"caption\":\"Case Vacanze Cefal\u00f9\"},\"image\":{\"@id\":\"https:\/\/casevacanzecefalu.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oceano - Case Vacanze Cefal\u00f9","description":"Appartamento di 50 mq a Cefal\u00f9 a pochi passi dal mare e dal centro storico ideale per la famiglia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/","og_locale":"de_DE","og_type":"article","og_title":"Oceano - Case Vacanze Cefal\u00f9","og_description":"Appartamento di 50 mq a Cefal\u00f9 a pochi passi dal mare e dal centro storico ideale per la famiglia","og_url":"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/","og_site_name":"Case Vacanze Cefal\u00f9","article_modified_time":"2023-03-19T18:21:58+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/casevacanzecefalu.com\/wp-content\/uploads\/2020\/06\/IMG_1392.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/","url":"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/","name":"Oceano - Case Vacanze Cefal\u00f9","isPartOf":{"@id":"https:\/\/casevacanzecefalu.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/#primaryimage"},"image":{"@id":"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/#primaryimage"},"thumbnailUrl":"https:\/\/casevacanzecefalu.com\/wp-content\/uploads\/2020\/06\/IMG_1392.jpg","datePublished":"2020-06-18T12:17:25+00:00","dateModified":"2023-03-19T18:21:58+00:00","description":"Appartamento di 50 mq a Cefal\u00f9 a pochi passi dal mare e dal centro storico ideale per la famiglia","breadcrumb":{"@id":"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/#primaryimage","url":"https:\/\/casevacanzecefalu.com\/wp-content\/uploads\/2020\/06\/IMG_1392.jpg","contentUrl":"https:\/\/casevacanzecefalu.com\/wp-content\/uploads\/2020\/06\/IMG_1392.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/casevacanzecefalu.com\/listing\/oceano-appartamento-cefalu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casevacanzecefalu.com\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/casevacanzecefalu.com\/listing\/"},{"@type":"ListItem","position":3,"name":"Oceano"}]},{"@type":"WebSite","@id":"https:\/\/casevacanzecefalu.com\/#website","url":"https:\/\/casevacanzecefalu.com\/","name":"Case Vacanze Cefal\u00f9","description":"affitto case ed appartamenti a Cefal\u00f9","publisher":{"@id":"https:\/\/casevacanzecefalu.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casevacanzecefalu.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/casevacanzecefalu.com\/#organization","name":"Case Vacanze Cefal\u00f9","url":"https:\/\/casevacanzecefalu.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/casevacanzecefalu.com\/#\/schema\/logo\/image\/","url":"https:\/\/casevacanzecefalu.com\/wp-content\/uploads\/2019\/12\/casevacanzacefalu.png","contentUrl":"https:\/\/casevacanzecefalu.com\/wp-content\/uploads\/2019\/12\/casevacanzacefalu.png","width":300,"height":73,"caption":"Case Vacanze Cefal\u00f9"},"image":{"@id":"https:\/\/casevacanzecefalu.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/casevacanzecefalu.com\/de\/wp-json\/wp\/v2\/listings\/2701"}],"collection":[{"href":"https:\/\/casevacanzecefalu.com\/de\/wp-json\/wp\/v2\/listings"}],"about":[{"href":"https:\/\/casevacanzecefalu.com\/de\/wp-json\/wp\/v2\/types\/listing"}],"author":[{"embeddable":true,"href":"https:\/\/casevacanzecefalu.com\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":16,"href":"https:\/\/casevacanzecefalu.com\/de\/wp-json\/wp\/v2\/listings\/2701\/revisions"}],"predecessor-version":[{"id":3561,"href":"https:\/\/casevacanzecefalu.com\/de\/wp-json\/wp\/v2\/listings\/2701\/revisions\/3561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casevacanzecefalu.com\/de\/wp-json\/wp\/v2\/media\/2729"}],"wp:attachment":[{"href":"https:\/\/casevacanzecefalu.com\/de\/wp-json\/wp\/v2\/media?parent=2701"}],"wp:term":[{"taxonomy":"listing_type","embeddable":true,"href":"https:\/\/casevacanzecefalu.com\/de\/wp-json\/wp\/v2\/listing_type?post=2701"},{"taxonomy":"room_type","embeddable":true,"href":"https:\/\/casevacanzecefalu.com\/de\/wp-json\/wp\/v2\/room_type?post=2701"},{"taxonomy":"listing_amenity","embeddable":true,"href":"https:\/\/casevacanzecefalu.com\/de\/wp-json\/wp\/v2\/amenities?post=2701"},{"taxonomy":"listing_facility","embeddable":true,"href":"https:\/\/casevacanzecefalu.com\/de\/wp-json\/wp\/v2\/facilities?post=2701"},{"taxonomy":"listing_country","embeddable":true,"href":"https:\/\/casevacanzecefalu.com\/de\/wp-json\/wp\/v2\/listing_countries?post=2701"},{"taxonomy":"listing_state","embeddable":true,"href":"https:\/\/casevacanzecefalu.com\/de\/wp-json\/wp\/v2\/listing_states?post=2701"},{"taxonomy":"listing_city","embeddable":true,"href":"https:\/\/casevacanzecefalu.com\/de\/wp-json\/wp\/v2\/listing_cities?post=2701"},{"taxonomy":"listing_area","embeddable":true,"href":"https:\/\/casevacanzecefalu.com\/de\/wp-json\/wp\/v2\/listing_areas?post=2701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}